

{"id":12814,"date":"2024-02-21T07:10:26","date_gmt":"2024-02-21T06:10:26","guid":{"rendered":"https:\/\/www.tv-neuhof.de\/wordpress\/?p=12814"},"modified":"2024-02-21T07:10:26","modified_gmt":"2024-02-21T06:10:26","slug":"damen-tsv-ost-mosheim-tv-jahn-neuhof-2128-1015","status":"publish","type":"post","link":"https:\/\/www.tv-neuhof.de\/wordpress\/2024\/02\/21\/damen-tsv-ost-mosheim-tv-jahn-neuhof-2128-1015\/","title":{"rendered":"Damen: TSV Ost-Mosheim \u2013 TV Jahn Neuhof 21:28 (10:15)"},"content":{"rendered":"\n<p><strong>Damen des TVN setzen Aufw\u00e4rtstrend fort<\/strong><!--more--><\/p>\n\n\n\n<p>Nach dem sehr gelungenen Fastnachtswochenende stand wieder Handball auf dem Programm. Gegner war der TSV Ost-Mosheim, welcher uns in der letzten Saison unsere einzigen Niederlagen zuf\u00fcgte. Die Vorzeichen standen eher schlecht, einige Krankheitsausf\u00e4lle und private Termine lie\u00dfen den sonst gro\u00dfen Kader auf 11 mehr oder weniger gesunde Spielerinnen zusammenschrumpfen.<\/p>\n\n\n\n<p>Entsprechend nerv\u00f6s starteten wir in die Partie und \u00fcber 3:0 und 5:2 setzte sich unser Gegner zun\u00e4chst etwas ab. Allerdings fanden in der Folge immer \u00f6fter die Abschl\u00fcsse auch ins Tor, sodass wir in der 10. Minute beim Stand von 5:5 erstmals ausgleichen konnten. Ein Vier-Tore-Lauf und Treffer von allen Positionen f\u00fchrte dann zu einem Halbzeitergebnis von 10:15.<\/p>\n\n\n\n<p>Nach dem Seitenwechsel arbeitete die Abwehr weiter konzentriert. Dahinter war eine gut aufgelegte Karo Frank im Tor ein sicherer R\u00fcckhalt, wenn doch mal ein Ball nicht erobert werden konnte. So wuchs der Vorsprung auf zeitweise 9 Tore an und alle mitgereisten Spielerinnen konnten Einsatzminuten sammeln.<\/p>\n\n\n\n<p>Am Ende stand ein ungef\u00e4hrdeter 21:28 Erfolg. Durch das zeitgleiche Unentschieden vom TV Hersfeld konnten wir uns in der Tabelle auf den 6. Platz verbessern und haben am n\u00e4chsten Wochenende in heimischer Halle gegen den TV Alsfeld die M\u00f6glichkeit, weiter an die oberen R\u00e4nge in der Tabelle heranzukommen. <\/p>\n\n\n\n<p>Es spielten:<br>Karo Frank (Tor), Lena Haas (Tor), Leonie Brunner (7), Antonia Kulla (7), Anna-Lena Heil (6), Luisa R\u00fcbsam (4), Sophie R\u00e4sch (4), Laura Kern, Paula Neumann, Isabell Roesler, Michelle Koch<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>&#8211; C. A. &#8211;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Damen des TVN setzen Aufw\u00e4rtstrend fort<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5,38],"tags":[58,60],"class_list":["post-12814","post","type-post","status-publish","format-standard","hentry","category-damen","category-spielbericht","tag-damen","tag-spielbericht"],"_links":{"self":[{"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/posts\/12814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/comments?post=12814"}],"version-history":[{"count":1,"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/posts\/12814\/revisions"}],"predecessor-version":[{"id":12815,"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/posts\/12814\/revisions\/12815"}],"wp:attachment":[{"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/media?parent=12814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/categories?post=12814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tv-neuhof.de\/wordpress\/wp-json\/wp\/v2\/tags?post=12814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}